{"id":723,"count":38,"description":"","link":"http:\/\/www.jordenrunt.nu\/resa\/tag\/djur\/","name":"djur","slug":"djur","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.jordenrunt.nu\/resa\/wp-json\/wp\/v2\/tags\/723"}],"collection":[{"href":"http:\/\/www.jordenrunt.nu\/resa\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.jordenrunt.nu\/resa\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.jordenrunt.nu\/resa\/wp-json\/wp\/v2\/posts?tags=723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}